{"id":11,"count":1,"description":"","link":"http:\/\/www.laligue85.org\/asso\/alco\/category\/lamicale\/","name":"L'amicale","slug":"lamicale","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"http:\/\/www.laligue85.org\/asso\/alco\/wp-json\/wp\/v2\/categories\/11"}],"collection":[{"href":"http:\/\/www.laligue85.org\/asso\/alco\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"http:\/\/www.laligue85.org\/asso\/alco\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"http:\/\/www.laligue85.org\/asso\/alco\/wp-json\/wp\/v2\/posts?categories=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}