{"id":8390,"date":"2018-11-28T18:28:12","date_gmt":"2018-11-28T17:28:12","guid":{"rendered":"http:\/\/www.laligue85.org\/fra\/?p=8390"},"modified":"2019-06-21T11:56:41","modified_gmt":"2019-06-21T09:56:41","slug":"prejuges-harcelement-reseaux-sociaux","status":"publish","type":"post","link":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/","title":{"rendered":"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux &#8211; Animation dans un lyc\u00e9e"},"content":{"rendered":"<p>Pendant plusieurs jours, Guillaume Allard, notre responsable mission jeunesse, \u00e9tait en intervention au lyc\u00e9e Val\u00e8re Math\u00e9 \u00e0 Olonne sur Mer.<\/p>\n<p>Les \u00e9l\u00e8ves de Seconde et de 3\u00e8me des diff\u00e9rentes fili\u00e8res de l&rsquo;\u00e9tablissement sont pr\u00e9sents. Ils sont divis\u00e9s en groupes de 15 personnes environ. Pendant 2h chaque groupe participe aux animations propos\u00e9es. Celles-ci \u00e9voquent, les discriminations et pr\u00e9jug\u00e9s ainsi que le harc\u00e8lement et les r\u00e9seaux sociaux. Ces interventions sont effectu\u00e9es dans le but de sensibiliser les jeunes \u00e0 des faits pouvant faire partie de leur quotidien.<\/p>\n<p>Diff\u00e9rentes activit\u00e9s ludiques et p\u00e9dagogiques sont propos\u00e9es sous 3 formes distinctes.<\/p>\n<h5>Cultionary<\/h5>\n<blockquote>\n<h5>\u00ab\u00a0Dessinez-moi \u00e7a&#8230;\u00a0\u00bb (Guillaume montre le mot \u00e0 crayonner aux dessinateurs) :<\/h5>\n<\/blockquote>\n<p>Tout d&rsquo;abord, la premi\u00e8re activit\u00e9 est un jeu o\u00f9 le principe est le m\u00eame que dans le pictionary ; un dessinateur dans chaque groupe doit faire deviner ce qu&rsquo;il esquisse. N\u00e9anmoins, il n&rsquo;a pas le droit d&rsquo;utiliser de symbole, de parler ou de mimer. Tout le monde participe \u00e0 tour de r\u00f4le en tant que dessinateur. Guillaume leur demande de dessiner \u00ab\u00a0un africain\u00a0\u00bb, \u00ab\u00a0un paysan\u00a0\u00bb, \u00ab\u00a0une personne homosexuelle\u00a0\u00bb,&#8230;\u00a0 Ensuite, tous les papiers sont dispers\u00e9s sur une table par mot interpr\u00e9t\u00e9.<\/p>\n<p>Une analyse par rapport \u00e0 la discrimination et aux pr\u00e9jug\u00e9s est donc anim\u00e9e. De ce fait, cela donne mati\u00e8re \u00e0 r\u00e9flexion puis am\u00e8ne \u00e0 la discussion.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"500\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 500px; height: 215px;\" data-original-width=\"500\" data-original-height=\"215\" > <div class=\"gallery-group images-1\" style=\"width: 328px; height: 215px;\" data-original-width=\"328\" data-original-height=\"215\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/explications-jeu-pictionnary-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"324\"> <meta itemprop=\"height\" content=\"211\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8391\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/explications-jeu-pictionnary-2-.jpeg\" data-orig-size=\"1016,660\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542363805&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.076923076923077&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"explications-jeu-pictionnary-2-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/explications-jeu-pictionnary-2--300x195.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/explications-jeu-pictionnary-2-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/explications-jeu-pictionnary-2-.jpeg?w=324&#038;h=211&#038;ssl=1\" width=\"324\" height=\"211\" data-original-width=\"324\" data-original-height=\"211\" itemprop=\"http:\/\/schema.org\/image\" title=\"explications-jeu-pictionnary-2-\" alt=\"explications-jeu-pictionnary-2-\" style=\"width: 324px; height: 211px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-2\" style=\"width: 172px; height: 215px;\" data-original-width=\"172\" data-original-height=\"215\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-dessin-mot-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"168\"> <meta itemprop=\"height\" content=\"111\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8395\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-mot-bis-.jpeg\" data-orig-size=\"1011,665\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542363832&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-dessin-mot-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-mot-bis--300x197.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-mot-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-mot-bis-.jpeg?w=168&#038;h=111&#038;ssl=1\" width=\"168\" height=\"111\" data-original-width=\"168\" data-original-height=\"111\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-dessin-mot-bis-\" alt=\"jeu-dessin-mot-bis-\" style=\"width: 168px; height: 111px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-dessin-deviner-3-bis-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"168\"> <meta itemprop=\"height\" content=\"96\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8406\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-3-bis-2-.jpeg\" data-orig-size=\"1012,579\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.8&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542364272&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;32&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.066666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-dessin-deviner-3-bis-2-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-3-bis-2--300x172.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-3-bis-2-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-3-bis-2-.jpeg?w=168&#038;h=96&#038;ssl=1\" width=\"168\" height=\"96\" data-original-width=\"168\" data-original-height=\"96\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-dessin-deviner-3-bis-2-\" alt=\"jeu-dessin-deviner-3-bis-2-\" style=\"width: 168px; height: 96px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 500px; height: 221px;\" data-original-width=\"500\" data-original-height=\"221\" > <div class=\"gallery-group images-2\" style=\"width: 166px; height: 221px;\" data-original-width=\"166\" data-original-height=\"221\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-dessin-deviner-2-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"162\"> <meta itemprop=\"height\" content=\"106\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8393\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-bis-.jpeg\" data-orig-size=\"1013,661\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542363933&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;30&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.05&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-dessin-deviner-2-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-bis--300x196.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-bis-.jpeg?w=162&#038;h=106&#038;ssl=1\" width=\"162\" height=\"106\" data-original-width=\"162\" data-original-height=\"106\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-dessin-deviner-2-bis-\" alt=\"jeu-dessin-deviner-2-bis-\" style=\"width: 162px; height: 106px;\" \/> <\/a> <\/div> <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-dessin-deviner-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"162\"> <meta itemprop=\"height\" content=\"107\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8392\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-.jpeg\" data-orig-size=\"1008,668\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;4&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542363866&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;20&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-dessin-deviner-2-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2--300x199.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessin-deviner-2-.jpeg?w=162&#038;h=107&#038;ssl=1\" width=\"162\" height=\"107\" data-original-width=\"162\" data-original-height=\"107\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-dessin-deviner-2-\" alt=\"jeu-dessin-deviner-2-\" style=\"width: 162px; height: 107px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 334px; height: 221px;\" data-original-width=\"334\" data-original-height=\"221\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-dessins-groupes-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"330\"> <meta itemprop=\"height\" content=\"217\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8396\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessins-groupes-bis-.jpeg\" data-orig-size=\"1013,666\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542364518&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.016666666666667&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-dessins-groupes-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessins-groupes-bis--300x197.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessins-groupes-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-dessins-groupes-bis-.jpeg?w=330&#038;h=217&#038;ssl=1\" width=\"330\" height=\"217\" data-original-width=\"330\" data-original-height=\"217\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-dessins-groupes-bis-\" alt=\"jeu-dessins-groupes-bis-\" style=\"width: 330px; height: 217px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<h5>Analyse vid\u00e9o sur l&rsquo;harc\u00e8lement :\u00a0 \u00a0<a href=\"https:\/\/www.dailymotion.com\/video\/xnutu3\">https:\/\/www.dailymotion.com\/video\/xnutu3<\/a><\/h5>\n<blockquote><p>Les injures &#8211; Agir contre le harc\u00e8lement \u00e0 l&rsquo;\u00e9cole<\/p><\/blockquote>\n<p>En premier lieu, Guillaume pr\u00e9cise que personne ne doit juger l&rsquo;autre. Chacun peut s&rsquo;exprimer sur le sujet ou se taire, ou m\u00eame quitter la salle si ce sujet est trop touchant pour eux.<\/p>\n<p>Puis, en lien avec les discriminations et pr\u00e9jug\u00e9s, \u00e0 partir d&rsquo;un film de sensibilisation du Minist\u00e8re de l&rsquo;\u00e9ducation nationale, les \u00e9l\u00e8ves analysent le comportement des personnes de la vid\u00e9o. Elle est visionn\u00e9e une premi\u00e8re fois.<\/p>\n<blockquote><p>En fait, on le fait aussi. On insulte un gars en passant \u00e0 c\u00f4t\u00e9 de lui, \u00e7a fait r\u00e9fl\u00e9chir&#8230;<\/p><\/blockquote>\n<p>Puis, une deuxi\u00e8me fois, avec par groupe un r\u00f4le d\u00e9termin\u00e9 pour que les jeunes puissent l&rsquo;analyser en d\u00e9tail. Ils r\u00e9pondent \u00e0 un questionnaire o\u00f9 il est demand\u00e9 de se mettre \u00e0 la place du personnage et de parler \u00e0 la premi\u00e8re personne. Une mise en commun est faite pour en discuter et en d\u00e9battre.<\/p>\n<h5>Les R\u00e9seaux Sociaux<\/h5>\n<blockquote><p>#Photos #PublicationsOuNon<\/p><\/blockquote>\n<p>Enfin, pour terminer ces 2h d&rsquo;actions, une enveloppe contenant des images post\u00e9es sur des r\u00e9seaux sociaux ou priv\u00e9es, est distribu\u00e9e. Chaque groupe dispose \u00e9galement d&rsquo;une feuille. Dessus est not\u00e9 : \u00ab\u00a0je publie sans soucis\u00a0\u00bb, \u00ab\u00a0je ne publie pas car c&rsquo;est ill\u00e9gal\u00a0\u00bb, \u00ab\u00a0je publie apr\u00e8s autorisation\u00a0\u00bb,je ne publie pas pour raison \u00e9thique&#8230;\u00a0\u00bb.\u00a0 Les \u00e9l\u00e8ves d\u00e9posent chaque photo dans l&rsquo;affirmation correspondante. Certaines images sont plus compliqu\u00e9es \u00e0 poser dans la phrase correspondante. En effet, leurs subtilit\u00e9s dans les mots et\/ou photos portent \u00e0 confusion.<\/p>\n<div class=\"tiled-gallery type-rectangular tiled-gallery-unresized\" data-original-width=\"500\" data-carousel-extra='null' itemscope itemtype=\"http:\/\/schema.org\/ImageGallery\" > <div class=\"gallery-row\" style=\"width: 500px; height: 152px;\" data-original-width=\"500\" data-original-height=\"152\" > <div class=\"gallery-group images-1\" style=\"width: 232px; height: 152px;\" data-original-width=\"232\" data-original-height=\"152\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-post-reseaux-sociaux-bilan-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"228\"> <meta itemprop=\"height\" content=\"148\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8400\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bilan-bis-.jpeg\" data-orig-size=\"1016,661\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542369654&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-post-r\u00e9seaux-sociaux-bilan-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bilan-bis--300x195.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bilan-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bilan-bis-.jpeg?w=228&#038;h=148&#038;ssl=1\" width=\"228\" height=\"148\" data-original-width=\"228\" data-original-height=\"148\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-post-r\u00e9seaux-sociaux-bilan-bis-\" alt=\"jeu-post-r\u00e9seaux-sociaux-bilan-bis-\" style=\"width: 228px; height: 148px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 268px; height: 152px;\" data-original-width=\"268\" data-original-height=\"152\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-post-reseaux-sociaux-3-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"264\"> <meta itemprop=\"height\" content=\"148\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8399\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-3-bis-.jpeg\" data-orig-size=\"1011,568\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;5.6&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542369443&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;22&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-post-r\u00e9seaux-sociaux-3-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-3-bis--300x169.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-3-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-3-bis-.jpeg?w=264&#038;h=148&#038;ssl=1\" width=\"264\" height=\"148\" data-original-width=\"264\" data-original-height=\"148\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-post-r\u00e9seaux-sociaux-3-bis-\" alt=\"jeu-post-r\u00e9seaux-sociaux-3-bis-\" style=\"width: 264px; height: 148px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <div class=\"gallery-row\" style=\"width: 500px; height: 133px;\" data-original-width=\"500\" data-original-height=\"133\" > <div class=\"gallery-group images-1\" style=\"width: 300px; height: 133px;\" data-original-width=\"300\" data-original-height=\"133\" > <div class=\"tiled-gallery-item tiled-gallery-item-large\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-post-reseaux-sociaux-2-bis-2\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"296\"> <meta itemprop=\"height\" content=\"129\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8398\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-2-bis-2-.jpeg\" data-orig-size=\"1017,444\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542369197&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;35&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.033333333333333&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-post-r\u00e9seaux-sociaux-2-bis-2-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-2-bis-2--300x131.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-2-bis-2-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-2-bis-2-.jpeg?w=296&#038;h=129&#038;ssl=1\" width=\"296\" height=\"129\" data-original-width=\"296\" data-original-height=\"129\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-post-r\u00e9seaux-sociaux-2-bis-2-\" alt=\"jeu-post-r\u00e9seaux-sociaux-2-bis-2-\" style=\"width: 296px; height: 129px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <div class=\"gallery-group images-1\" style=\"width: 200px; height: 133px;\" data-original-width=\"200\" data-original-height=\"133\" > <div class=\"tiled-gallery-item tiled-gallery-item-small\" itemprop=\"associatedMedia\" itemscope itemtype=\"http:\/\/schema.org\/ImageObject\"> <a href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/jeu-post-reseaux-sociaux-bis\/\" border=\"0\" itemprop=\"url\"> <meta itemprop=\"width\" content=\"196\"> <meta itemprop=\"height\" content=\"129\"> <img loading=\"lazy\" decoding=\"async\" data-attachment-id=\"8401\" data-orig-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg\" data-orig-size=\"1012,665\" data-comments-opened=\"\" data-image-meta=\"{&quot;aperture&quot;:&quot;3.5&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;NIKON D3100&quot;,&quot;caption&quot;:&quot;????????????????????????????????????&quot;,&quot;created_timestamp&quot;:&quot;1542369132&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;18&quot;,&quot;iso&quot;:&quot;800&quot;,&quot;shutter_speed&quot;:&quot;0.02&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;1&quot;}\" data-image-title=\"jeu-post-r\u00e9seaux-sociaux-bis-\" data-image-description=\"\" data-medium-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis--300x197.jpeg\" data-large-file=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg\" src=\"https:\/\/i0.wp.com\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg?w=196&#038;h=129&#038;ssl=1\" width=\"196\" height=\"129\" data-original-width=\"196\" data-original-height=\"129\" itemprop=\"http:\/\/schema.org\/image\" title=\"jeu-post-r\u00e9seaux-sociaux-bis-\" alt=\"jeu-post-r\u00e9seaux-sociaux-bis-\" style=\"width: 196px; height: 129px;\" \/> <\/a> <\/div> <\/div> <!-- close group --> <\/div> <!-- close row --> <\/div>\n<p>Ces animations termin\u00e9es, un bilan est men\u00e9 \u00e0 bien. Ceci a permis de sensibiliser le groupe \u00e0 ces situations et inciter aux changements de comportement.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: right;\">\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 Coralie Caill\u00e9, Web Reporter en Service Civique.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pendant plusieurs jours, Guillaume Allard, notre responsable mission jeunesse, \u00e9tait en intervention au lyc\u00e9e Val\u00e8re Math\u00e9 \u00e0 Olonne sur Mer. Les \u00e9l\u00e8ves de Seconde et de 3\u00e8me des diff\u00e9rentes fili\u00e8res de l&rsquo;\u00e9tablissement sont pr\u00e9sents. Ils sont divis\u00e9s en groupes de 15 personnes environ. Pendant 2h chaque groupe participe aux animations [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":8401,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"footnotes":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":[]},"categories":[326,158],"tags":[270,277,272,273],"class_list":["post-8390","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-education-aux-medias","category-racisme-et-lutte-contre-les-discriminations","tag-etablissements-scolaires","tag-jeunesse","tag-lutte-contre-les-discriminations","tag-outils-pedagogiques"],"jetpack_publicize_connections":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e\" \/>\n<meta property=\"og:description\" content=\"Pendant plusieurs jours, Guillaume Allard, notre responsable mission jeunesse, \u00e9tait en intervention au lyc\u00e9e Val\u00e8re Math\u00e9 \u00e0 Olonne sur Mer. Les \u00e9l\u00e8ves de Seconde et de 3\u00e8me des diff\u00e9rentes fili\u00e8res de l&rsquo;\u00e9tablissement sont pr\u00e9sents. Ils sont divis\u00e9s en groupes de 15 personnes environ. Pendant 2h chaque groupe participe aux animations [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/\" \/>\n<meta property=\"og:site_name\" content=\"La Ligue de l&#039;Enseignement de Vend\u00e9e\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-28T17:28:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-06-21T09:56:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1012\" \/>\n\t<meta property=\"og:image:height\" content=\"665\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"webreporter\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"webreporter\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/\",\"url\":\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/\",\"name\":\"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e\",\"isPartOf\":{\"@id\":\"https:\/\/www.laligue85.org\/fra\/#website\"},\"datePublished\":\"2018-11-28T17:28:12+00:00\",\"dateModified\":\"2019-06-21T09:56:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/1e7451bdc7326a9d6998c4e6143ef302\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.laligue85.org\/fra\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux &#8211; Animation dans un lyc\u00e9e\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.laligue85.org\/fra\/#website\",\"url\":\"https:\/\/www.laligue85.org\/fra\/\",\"name\":\"La Ligue de l&#039;Enseignement de Vend\u00e9e\",\"description\":\"F\u00e9d\u00e9ration d&#039;\u00e9ducation populaire\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.laligue85.org\/fra\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/1e7451bdc7326a9d6998c4e6143ef302\",\"name\":\"webreporter\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/bb1e730a8d65ed9caef9b25f341b72a8?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/bb1e730a8d65ed9caef9b25f341b72a8?s=96&d=mm&r=g\",\"caption\":\"webreporter\"},\"url\":\"https:\/\/www.laligue85.org\/fra\/blog\/author\/webreporter\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/","og_locale":"fr_FR","og_type":"article","og_title":"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e","og_description":"Pendant plusieurs jours, Guillaume Allard, notre responsable mission jeunesse, \u00e9tait en intervention au lyc\u00e9e Val\u00e8re Math\u00e9 \u00e0 Olonne sur Mer. Les \u00e9l\u00e8ves de Seconde et de 3\u00e8me des diff\u00e9rentes fili\u00e8res de l&rsquo;\u00e9tablissement sont pr\u00e9sents. Ils sont divis\u00e9s en groupes de 15 personnes environ. Pendant 2h chaque groupe participe aux animations [&hellip;]","og_url":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/","og_site_name":"La Ligue de l&#039;Enseignement de Vend\u00e9e","article_published_time":"2018-11-28T17:28:12+00:00","article_modified_time":"2019-06-21T09:56:41+00:00","og_image":[{"width":1012,"height":665,"url":"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg","type":"image\/jpeg"}],"author":"webreporter","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"webreporter","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/","url":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/","name":"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux - Animation dans un lyc\u00e9e - La Ligue de l&#039;Enseignement de Vend\u00e9e","isPartOf":{"@id":"https:\/\/www.laligue85.org\/fra\/#website"},"datePublished":"2018-11-28T17:28:12+00:00","dateModified":"2019-06-21T09:56:41+00:00","author":{"@id":"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/1e7451bdc7326a9d6998c4e6143ef302"},"breadcrumb":{"@id":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.laligue85.org\/fra\/blog\/2018\/11\/28\/prejuges-harcelement-reseaux-sociaux\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.laligue85.org\/fra\/"},{"@type":"ListItem","position":2,"name":"Pr\u00e9jug\u00e9s, harc\u00e8lement et r\u00e9seaux sociaux &#8211; Animation dans un lyc\u00e9e"}]},{"@type":"WebSite","@id":"https:\/\/www.laligue85.org\/fra\/#website","url":"https:\/\/www.laligue85.org\/fra\/","name":"La Ligue de l&#039;Enseignement de Vend\u00e9e","description":"F\u00e9d\u00e9ration d&#039;\u00e9ducation populaire","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.laligue85.org\/fra\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/1e7451bdc7326a9d6998c4e6143ef302","name":"webreporter","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.laligue85.org\/fra\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/bb1e730a8d65ed9caef9b25f341b72a8?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/bb1e730a8d65ed9caef9b25f341b72a8?s=96&d=mm&r=g","caption":"webreporter"},"url":"https:\/\/www.laligue85.org\/fra\/blog\/author\/webreporter\/"}]}},"jetpack_featured_media_url":"https:\/\/www.laligue85.org\/fra\/wp-content\/uploads\/2018\/11\/jeu-post-r\u00e9seaux-sociaux-bis-.jpeg","jetpack_shortlink":"https:\/\/wp.me\/p9Chnq-2bk","_links":{"self":[{"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/posts\/8390","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/comments?post=8390"}],"version-history":[{"count":20,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/posts\/8390\/revisions"}],"predecessor-version":[{"id":9827,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/posts\/8390\/revisions\/9827"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/media\/8401"}],"wp:attachment":[{"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/media?parent=8390"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/categories?post=8390"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.laligue85.org\/fra\/wp-json\/wp\/v2\/tags?post=8390"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}